{"id":39,"count":1,"description":"","link":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/","name":"cestovanie","slug":"cestovanie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arch\u00edvy cestovanie - Seamore | Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arch\u00edvy cestovanie - Seamore | Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/\" \/>\n<meta property=\"og:site_name\" content=\"Seamore | Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/\",\"url\":\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/\",\"name\":\"Arch\u00edvy cestovanie - Seamore | Blog\",\"isPartOf\":{\"@id\":\"https:\/\/seamore.sk\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/#breadcrumb\"},\"inLanguage\":\"sk-SK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Domovsk\u00e1 str\u00e1nka\",\"item\":\"https:\/\/seamore.sk\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cestovanie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seamore.sk\/blog\/#website\",\"url\":\"https:\/\/seamore.sk\/blog\/\",\"name\":\"Seamore | Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/seamore.sk\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seamore.sk\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/seamore.sk\/blog\/#organization\",\"name\":\"Seamore | Blog\",\"url\":\"https:\/\/seamore.sk\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/seamore.sk\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/seamore.sk\/blog\/wp-content\/uploads\/2021\/12\/logo.svg\",\"contentUrl\":\"https:\/\/seamore.sk\/blog\/wp-content\/uploads\/2021\/12\/logo.svg\",\"width\":219,\"height\":102,\"caption\":\"Seamore | Blog\"},\"image\":{\"@id\":\"https:\/\/seamore.sk\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arch\u00edvy cestovanie - Seamore | Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/","og_locale":"sk_SK","og_type":"article","og_title":"Arch\u00edvy cestovanie - Seamore | Blog","og_url":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/","og_site_name":"Seamore | Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/","url":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/","name":"Arch\u00edvy cestovanie - Seamore | Blog","isPartOf":{"@id":"https:\/\/seamore.sk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/#breadcrumb"},"inLanguage":"sk-SK"},{"@type":"BreadcrumbList","@id":"https:\/\/seamore.sk\/blog\/tag\/cestovanie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Domovsk\u00e1 str\u00e1nka","item":"https:\/\/seamore.sk\/blog\/"},{"@type":"ListItem","position":2,"name":"cestovanie"}]},{"@type":"WebSite","@id":"https:\/\/seamore.sk\/blog\/#website","url":"https:\/\/seamore.sk\/blog\/","name":"Seamore | Blog","description":"","publisher":{"@id":"https:\/\/seamore.sk\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seamore.sk\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/seamore.sk\/blog\/#organization","name":"Seamore | Blog","url":"https:\/\/seamore.sk\/blog\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/seamore.sk\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/seamore.sk\/blog\/wp-content\/uploads\/2021\/12\/logo.svg","contentUrl":"https:\/\/seamore.sk\/blog\/wp-content\/uploads\/2021\/12\/logo.svg","width":219,"height":102,"caption":"Seamore | Blog"},"image":{"@id":"https:\/\/seamore.sk\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/seamore.sk\/blog\/wp-json\/wp\/v2\/tags\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seamore.sk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/seamore.sk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/seamore.sk\/blog\/wp-json\/wp\/v2\/posts?tags=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}